{"id":13128,"date":"2022-12-04T12:54:00","date_gmt":"2022-12-04T12:54:00","guid":{"rendered":"https:\/\/bookiessite.com\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b8%a5%e0%b8%b1%e0%b8%9a%e0%b8%ab%e0%b8%81%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a3-%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b9%83%e0%b8%8a%e0%b9%89\/"},"modified":"2022-12-04T12:54:00","modified_gmt":"2022-12-04T12:54:00","slug":"%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b8%a5%e0%b8%b1%e0%b8%9a%e0%b8%ab%e0%b8%81%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a3-%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b9%83%e0%b8%8a%e0%b9%89","status":"publish","type":"post","link":"https:\/\/bookiessite.com\/th\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b8%a5%e0%b8%b1%e0%b8%9a%e0%b8%ab%e0%b8%81%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a3-%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b9%83%e0%b8%8a%e0%b9%89\/","title":{"rendered":"\u0e04\u0e27\u0e32\u0e21\u0e25\u0e31\u0e1a\u0e2b\u0e01\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e23 \u0e27\u0e34\u0e18\u0e35\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e35\u0e40\u0e02\u0e35\u0e22\u0e27\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e33\u0e44\u0e23 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c"},"content":{"rendered":"<p>\u0e2a\u0e35\u0e43\u0e14\u0e46 \u0e08\u0e30\u0e14\u0e39\u0e14\u0e35\u0e14\u0e49\u0e27\u0e22\u0e14\u0e27\u0e07\u0e15\u0e32\u0e2a\u0e35\u0e19\u0e49\u0e33\u0e15\u0e32\u0e25\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e35\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07\u0e2d\u0e33\u0e1e\u0e31\u0e19 \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e2a\u0e35\u0e14\u0e33\u0e41\u0e1a\u0e1a\u0e14\u0e31\u0e49\u0e07\u0e40\u0e14\u0e34\u0e21\u0e44\u0e1b\u0e08\u0e19\u0e16\u0e36\u0e07\u0e42\u0e17\u0e19\u0e2a\u0e35\u0e2a\u0e27\u0e48\u0e32\u0e07\u0e01\u0e27\u0e48\u0e32 RedChigan \u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e34\u0e19\u0e2d\u0e48\u0e2d\u0e19\u0e1b\u0e23\u0e30\u0e2b\u0e25\u0e32\u0e14\u0e17\u0e35\u0e48\u0e21\u0e35\u0e25\u0e27\u0e14\u0e25\u0e32\u0e22\u0e2a\u0e35\u0e02\u0e32\u0e27\u0e41\u0e25\u0e30\u0e2d\u0e31\u0e19\u0e40\u0e14\u0e2d\u0e23\u0e4c\u0e42\u0e17\u0e19\u0e2a\u0e35\u0e14\u0e33 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e04\u0e38\u0e13\u0e22\u0e31\u0e07\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e09\u0e32\u0e01\u0e14\u0e23\u0e32\u0e21\u0e48\u0e32\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e2b\u0e34\u0e19\u0e2d\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e18\u0e35\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e25\u0e32\u0e07\u0e44\u0e14\u0e49\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22 \u0e04\u0e38\u0e13\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e21\u0e34\u0e15\u0e34\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e42\u0e15\u0e4a\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e1b\u0e49\u0e07\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e44\u0e14\u0e49\u0e40\u0e0a\u0e48\u0e19\u0e01\u0e31\u0e19\u0e42\u0e14\u0e22\u0e43\u0e2a\u0e48 knicks and knacks \u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\u0e1a\u0e19\u0e16\u0e32\u0e14\u0e2b\u0e34\u0e19\u0e2d\u0e48\u0e2d\u0e19 \u0e2b\u0e34\u0e19\u0e2d\u0e48\u0e2d\u0e19\u0e2a\u0e35\u0e41\u0e14\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2b\u0e49\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27\u0e15\u0e49\u0e2d\u0e07\u0e21\u0e35\u0e40\u0e2a\u0e16\u0e35\u0e22\u0e23\u0e20\u0e32\u0e1e\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\u0e14\u0e49\u0e27\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e04\u0e23\u0e31\u0e27\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e43\u0e19\u0e17\u0e33\u0e19\u0e2d\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19 \u0e01\u0e32\u0e23\u0e40\u0e2a\u0e34\u0e23\u0e4c\u0e1f\u0e1a\u0e2d\u0e23\u0e4c\u0e14\u0e17\u0e35\u0e48\u0e21\u0e35\u0e02\u0e19\u0e32\u0e14\u0e41\u0e25\u0e30\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e35\u0e48\u0e23\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e01\u0e47\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e1a\u0e1a\u0e21\u0e35\u0e1d\u0e32\u0e1b\u0e34\u0e14 \u0e41\u0e01\u0e49\u0e27 \u0e42\u0e16\u0e40\u0e01\u0e47\u0e1a\u0e02\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2b\u0e49\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27\u0e41\u0e25\u0e30\u0e2b\u0e49\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e21\u0e32\u0e01\u0e21\u0e32\u0e22 \u0e08\u0e30\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e25\u0e38\u0e04\u0e17\u0e35\u0e48\u0e14\u0e39\u0e2d\u0e1a\u0e2d\u0e38\u0e48\u0e19\u0e14\u0e49\u0e27\u0e22\u0e2a\u0e35\u0e17\u0e35\u0e48\u0e2b\u0e49\u0e2d\u0e22\u0e41\u0e25\u0e30\u0e25\u0e27\u0e14\u0e25\u0e32\u0e22\u0e17\u0e35\u0e48\u0e21\u0e2d\u0e07\u0e40\u0e2b\u0e47\u0e19\u0e44\u0e14\u0e49\u0e1a\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e1c\u0e34\u0e27 \u0e41\u0e21\u0e49\u0e27\u0e48\u0e32\u0e08\u0e30\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48 Surface Laptop \u0e41\u0e15\u0e48 Surface Pro \u0e22\u0e31\u0e07\u0e04\u0e07\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e14\u0e35\u0e2b\u0e32\u0e01\u0e04\u0e38\u0e13\u0e01\u0e33\u0e25\u0e31\u0e07\u0e21\u0e2d\u0e07\u0e2b\u0e32\u0e41\u0e17\u0e47\u0e1a\u0e40\u0e25\u0e47\u0e15 Windows \u0e17\u0e35\u0e48\u0e17\u0e33\u0e44\u0e14\u0e49\u0e17\u0e38\u0e01\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e0b\u0e36\u0e48\u0e07\u0e17\u0e33\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e41\u0e25\u0e47\u0e1b\u0e17\u0e47\u0e2d\u0e1b Windows \u0e44\u0e14\u0e49\u0e2a\u0e2d\u0e07\u0e40\u0e17\u0e48\u0e32 \u0e40\u0e27\u0e47\u0e1a\u0e1a\u0e25\u0e47\u0e2d\u0e01\u0e43\u0e19\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21\u0e17\u0e35\u0e48\u0e08\u0e31\u0e14\u0e17\u0e33\u0e42\u0e14\u0e22 Microsoft \u0e23\u0e30\u0e1a\u0e38 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e04\u0e32\u0e14\u0e27\u0e48\u0e32 &#8220;\u0e17\u0e38\u0e01\u0e22\u0e39\u0e19\u0e34\u0e15\u0e17\u0e35\u0e48\u0e21\u0e35\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c\u0e08\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e1f\u0e23\u0e35\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a Windows eleven \u0e20\u0e32\u0e22\u0e43\u0e19\u0e01\u0e25\u0e32\u0e07\u0e1b\u0e35 \u200b\u200b2565&#8221; \u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e23\u0e2d\u0e2d\u0e35\u0e01\u0e04\u0e23\u0e36\u0e48\u0e07\u0e1b\u0e35\u0e2b\u0e23\u0e37\u0e2d<\/p>\n<p>\u0e1e\u0e27\u0e01\u0e40\u0e02\u0e32\u0e21\u0e35\u0e04\u0e2d\u0e25\u0e40\u0e25\u0e47\u0e01\u0e0a\u0e31\u0e48\u0e19\u0e2b\u0e34\u0e19\u0e2d\u0e48\u0e2d\u0e19\u0e2a\u0e35\u0e41\u0e14\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\u0e41\u0e25\u0e30\u0e41\u0e1b\u0e25\u0e01\u0e15\u0e32\u0e0b\u0e36\u0e48\u0e07\u0e04\u0e38\u0e13\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e40\u0e2d\u0e07 \u0e2b\u0e34\u0e19\u0e2d\u0e48\u0e2d\u0e19\u0e2a\u0e35\u0e41\u0e14\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e34\u0e19\u0e2a\u0e35\u0e41\u0e14\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\u0e0b\u0e36\u0e48\u0e07\u0e40\u0e01\u0e34\u0e14\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e15\u0e01\u0e1c\u0e25\u0e36\u0e01\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34\u0e02\u0e2d\u0e07\u0e2b\u0e34\u0e19\u0e1b\u0e39\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e17\u0e35\u0e48\u0e40\u0e02\u0e49\u0e32\u0e01\u0e31\u0e1a\u0e1e\u0e23\u0e21\u0e2b\u0e23\u0e37\u0e2d\u0e42\u0e0b\u0e1f\u0e32\u0e2b\u0e25\u0e32\u0e01\u0e2a\u0e35 \u0e44\u0e21\u0e49\u0e01\u0e23\u0e30\u0e16\u0e32\u0e07 \u0e42\u0e15\u0e4a\u0e30\u0e44\u0e21\u0e49 \u0e41\u0e25\u0e30\u0e42\u0e04\u0e21\u0e44\u0e1f\u0e01\u0e47\u0e40\u0e02\u0e49\u0e32\u0e01\u0e31\u0e19\u0e44\u0e14\u0e49\u0e14\u0e35\u0e01\u0e31\u0e1a\u0e2b\u0e34\u0e19\u0e2a\u0e35\u0e40\u0e02\u0e49\u0e21 \u0e01\u0e23\u0e30\u0e42\u0e08\u0e19\u0e43\u0e2a\u0e48\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e44\u0e2e\u0e42\u0e0b\u0e41\u0e25\u0e30\u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e43\u0e2b\u0e21\u0e48\u0e44\u0e14\u0e49\u0e43\u0e19\u0e17\u0e31\u0e19\u0e17\u0e35 &#8220;\u0e21\u0e38\u0e21\u0e44\u0e1a\u0e21\u0e32\u0e01\u0e40\u0e01\u0e34\u0e19\u0e44\u0e1b&#8221; \u0e41\u0e25\u0e30 &#8220;\u0e27\u0e32\u0e44\u0e0b\u0e2a\u0e39\u0e07&#8221; \u0e40\u0e23\u0e35\u0e22\u0e01\u0e27\u0e48\u0e32\u0e2d\u0e30\u0e44\u0e23 \u0e17\u0e23\u0e31\u0e21\u0e1b\u0e4c\u0e01\u0e25\u0e48\u0e32\u0e27\u0e16\u0e36\u0e07\u0e04\u0e27\u0e32\u0e21\u0e25\u0e49\u0e21\u0e40\u0e2b\u0e25\u0e27\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e34\u0e14\u0e1e\u0e23\u0e21\u0e41\u0e14\u0e19\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e23\u0e48\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e42\u0e23\u0e04 \u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19 &#8220;\u0e42\u0e28\u0e01\u0e19\u0e32\u0e0f\u0e01\u0e23\u0e23\u0e21\u0e04\u0e23\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e0d\u0e48&#8221; \u0e21\u0e32\u0e01\u0e21\u0e32\u0e22\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e41\u0e23\u0e01\u0e46 \u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e40\u0e08\u0e47\u0e1a\u0e1b\u0e48\u0e27\u0e22 \u0e43\u0e04\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e04\u0e34\u0e14\u0e04\u0e49\u0e19\u0e01\u0e35\u0e2c\u0e32\u0e17\u0e35\u0e48\u0e40\u0e23\u0e35\u0e22\u0e01\u0e27\u0e48\u0e32\u0e1f\u0e38\u0e15\u0e1a\u0e2d\u0e25? Vander Graaf \u0e1c\u0e39\u0e49\u0e0b\u0e36\u0e48\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32\u0e40\u0e02\u0e32\u0e16\u0e39\u0e01\u0e44\u0e25\u0e48\u0e2d\u0e2d\u0e01\u0e43\u0e19\u0e1b\u0e35 2014 \u0e42\u0e14\u0e22\u0e1a\u0e35.\u0e0b\u0e35. \u0e40\u0e2d\u0e47\u0e21\u0e21\u0e32\u0e0b\u0e36\u0e48\u0e07\u0e25\u0e07\u0e17\u0e38\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e2b\u0e38\u0e49\u0e19\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e40\u0e18\u0e2d\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32\u0e1e\u0e27\u0e01\u0e40\u0e02\u0e32\u0e15\u0e23\u0e30\u0e2b\u0e19\u0e31\u0e01\u0e27\u0e48\u0e32\u0e21\u0e35\u0e2a\u0e34\u0e48\u0e07\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e17\u0e35\u0e48\u0e1c\u0e34\u0e14\u0e1e\u0e25\u0e32\u0e14\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e07\u0e34\u0e19\u0e1d\u0e32\u0e01 7,000 \u0e14\u0e2d\u0e25\u0e25\u0e32\u0e23\u0e4c\u0e2a\u0e38\u0e14\u0e17\u0e49\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e40\u0e18\u0e2d\u0e15\u0e35\u0e01\u0e25\u0e31\u0e1a \u0e14\u0e31\u0e07\u0e19\u0e31\u0e49\u0e19 \u0e2b\u0e32\u0e01\u0e04\u0e38\u0e13\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1c\u0e25\u0e15\u0e2d\u0e1a\u0e41\u0e17\u0e19\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e43\u0e19\u0e02\u0e13\u0e30\u0e17\u0e35\u0e48\u0e01\u0e33\u0e25\u0e31\u0e07\u0e40\u0e25\u0e48\u0e19\u0e2a\u0e19\u0e38\u0e01\u0e01\u0e31\u0e1a\u0e42\u0e25\u0e01\u0e02\u0e2d\u0e07\u0e04\u0e23\u0e34\u0e1b\u0e42\u0e15 \u0e01\u0e32\u0e23\u0e1d\u0e32\u0e01\u0e40\u0e07\u0e34\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e27\u0e34\u0e18\u0e35\u0e17\u0e35\u0e48\u0e22\u0e2d\u0e14\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e38\u0e13\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e1c\u0e25\u0e15\u0e2d\u0e1a\u0e41\u0e17\u0e19\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e32\u0e01 \u0e2b\u0e34\u0e19\u0e2d\u0e48\u0e2d\u0e19\u0e2a\u0e35\u0e41\u0e14\u0e07\u0e21\u0e35\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e2a\u0e34\u0e49\u0e19\u0e2a\u0e38\u0e14\u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e43\u0e0a\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e16\u0e39\u0e01\u0e27\u0e34\u0e18\u0e35 \u0e0a\u0e38\u0e14\u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e23\u0e37\u0e2d\u0e0a\u0e32\u0e21\u0e25\u0e32\u0e22\u0e2b\u0e34\u0e19\u0e2d\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e27\u0e32\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e1a\u0e19\u0e41\u0e1c\u0e48\u0e19\u0e44\u0e21\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e27\u0e34\u0e18\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e41\u0e1a\u0e1a\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e28<\/p>\n<p>\u0e1e\u0e27\u0e01\u0e40\u0e02\u0e32\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e2b\u0e34\u0e19\u0e2d\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e41\u0e25\u0e30\u0e21\u0e35\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e21\u0e32\u0e01\u0e40\u0e01\u0e34\u0e19\u0e44\u0e1b\u0e08\u0e32\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e31\u0e48\u0e27\u0e42\u0e25\u0e01 \u0e1e\u0e27\u0e01\u0e40\u0e02\u0e32\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e04\u0e2d\u0e25\u0e40\u0e25\u0e01\u0e0a\u0e31\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\u0e02\u0e2d\u0e07\u0e2b\u0e34\u0e19\u0e2d\u0e48\u0e2d\u0e19\u0e2a\u0e35\u0e41\u0e14\u0e07\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e2b\u0e25\u0e32\u0e22\u0e2a\u0e35\u0e17\u0e35\u0e48\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e40\u0e17\u0e48\u0e32\u0e01\u0e31\u0e1a\u0e2a\u0e35\u0e14\u0e33 \u0e2a\u0e35\u0e02\u0e32\u0e27 \u0e2a\u0e35\u0e40\u0e1a\u0e08 \u0e2a\u0e35\u0e40\u0e02\u0e35\u0e22\u0e27 \u0e2a\u0e35\u0e19\u0e49\u0e33\u0e15\u0e32\u0e25\u0e41\u0e25\u0e30\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e2a\u0e35\u0e2a\u0e31\u0e19\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e14\u0e49\u0e27\u0e22\u0e09\u0e32\u0e01\u0e01\u0e31\u0e49\u0e19\u0e2b\u0e34\u0e19\u0e2d\u0e48\u0e2d\u0e19\u0e40\u0e14\u0e35\u0e48\u0e22\u0e27 \u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e31\u0e48\u0e07\u0e40\u0e25\u0e48\u0e19\u0e21\u0e35\u0e2a\u0e35\u0e2a\u0e31\u0e19\u0e2a\u0e14\u0e43\u0e2a \u0e41\u0e15\u0e48\u0e2d\u0e22\u0e48\u0e32\u0e25\u0e31\u0e07\u0e40\u0e25\u0e17\u0e35\u0e48\u0e08\u0e30\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e15\u0e31\u0e27\u0e14\u0e49\u0e27\u0e22\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e34\u0e19\u0e2d\u0e48\u0e2d\u0e19\u0e2a\u0e35\u0e41\u0e14\u0e07 \u0e17\u0e35\u0e48\u0e43\u0e2a\u0e48\u0e01\u0e38\u0e0d\u0e41\u0e08\u0e02\u0e19\u0e32\u0e14\u0e40\u0e25\u0e47\u0e01\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e2d\u0e31\u0e14\u0e41\u0e19\u0e48\u0e19\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22\u0e25\u0e39\u0e01\u0e1a\u0e2d\u0e25\u0e2b\u0e34\u0e19\u0e2d\u0e48\u0e2d\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e49\u0e2d\u0e19\u0e01\u0e23\u0e27\u0e14\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e15\u0e34\u0e21\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e0a\u0e35\u0e27\u0e32\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e42\u0e15\u0e4a\u0e30\u0e44\u0e14\u0e49 \u0e41\u0e2d\u0e1e Mimo \u0e02\u0e2d\u0e07 DJI \u0e01\u0e47\u0e40\u0e15\u0e47\u0e21\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22\u0e15\u0e31\u0e27\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e40\u0e0a\u0e48\u0e19\u0e01\u0e31\u0e19 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1f\u0e35\u0e40\u0e08\u0e2d\u0e23\u0e4c ActiveTrack 3.Zero \u0e17\u0e35\u0e48\u0e43\u0e2b\u0e49\u0e04\u0e38\u0e13\u0e27\u0e32\u0e14\u0e01\u0e23\u0e2d\u0e1a\u0e23\u0e2d\u0e1a\u0e46 \u0e2b\u0e31\u0e27\u0e02\u0e49\u0e2d\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13 \u0e41\u0e25\u0e30\u0e21\u0e31\u0e19\u0e08\u0e30\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e1e\u0e27\u0e01\u0e21\u0e31\u0e19\u0e17\u0e31\u0e19\u0e17\u0e35 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49 \u0e04\u0e38\u0e13\u0e22\u0e31\u0e07\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e41\u0e19\u0e30\u0e19\u0e33\u0e01\u0e32\u0e23\u0e08\u0e2d\u0e07\u0e1c\u0e48\u0e32\u0e19\u0e41\u0e2d\u0e1b\u0e41\u0e17\u0e19\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e01\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e0b\u0e36\u0e48\u0e07\u0e08\u0e30\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33\u0e02\u0e19\u0e32\u0e14\u0e40\u0e25\u0e47\u0e01\u0e14\u0e39\u0e21\u0e35\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e44\u0e14\u0e49 \u0e2b\u0e32\u0e01\u0e04\u0e38\u0e13\u0e15\u0e31\u0e49\u0e07\u0e43\u0e08\u0e08\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e17\u0e35\u0e48\u0e2b\u0e23\u0e39\u0e2b\u0e23\u0e32\u0e41\u0e25\u0e30\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e01\u0e1c\u0e48\u0e2d\u0e19\u0e2b\u0e22\u0e48\u0e2d\u0e19\u0e43\u0e08\u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e17\u0e32\u0e07\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e35\u0e49 \u0e04\u0e38\u0e13\u0e2d\u0e32\u0e08\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e23\u0e32\u0e23\u0e16\u0e19\u0e32\u0e1a\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e0a\u0e48\u0e19\u0e19\u0e35\u0e49: \u0e0b\u0e35\u0e2d\u0e35\u0e42\u0e2d\u0e02\u0e2d\u0e07 Fortune 500 \u0e2a\u0e2d\u0e07\u0e04\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e1a\u0e49\u0e32\u0e19, \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32 2,000 \u0e40\u0e2d\u0e40\u0e04\u0e2d\u0e23\u0e4c\u0e43\u0e19\u0e44\u0e21\u0e48\u0e01\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e17\u0e35\u0e48\u0e2d\u0e32\u0e08\u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e17\u0e35\u0e48\u0e40\u0e01\u0e48\u0e32\u0e41\u0e01\u0e48\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e43\u0e19\u0e2d\u0e40\u0e21\u0e23\u0e34\u0e01\u0e32, \u0e41\u0e25\u0e30\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e39\u0e1b\u0e42\u0e20\u0e04\u0e40\u0e01\u0e37\u0e2d\u0e1a 10 \u0e44\u0e21\u0e25\u0e4c\u0e17\u0e35\u0e48\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e40\u0e23\u0e47\u0e27\u0e01\u0e27\u0e48\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e2b\u0e25\u0e31\u0e01 \u0e1a\u0e49\u0e32\u0e19\u0e16\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e02\u0e36\u0e49\u0e19<\/p>\n<p>\u0e14\u0e39\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e27\u0e48\u0e32 Triller \u0e08\u0e30\u0e40\u0e02\u0e49\u0e32\u0e01\u0e31\u0e19\u0e44\u0e14\u0e49\u0e14\u0e35\u0e01\u0e31\u0e1a PPV \u0e04\u0e31\u0e19\u0e19\u0e35\u0e49 \u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e17\u0e32\u0e07\u0e40\u0e02\u0e49\u0e32 \u0e2b\u0e49\u0e2d\u0e07\u0e42\u0e16\u0e07 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e25\u0e47\u0e2d\u0e1a\u0e1a\u0e35\u0e49\u0e02\u0e2d\u0e07\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e0a\u0e48\u0e27\u0e22\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28\u0e17\u0e35\u0e48\u0e2d\u0e1a\u0e2d\u0e38\u0e48\u0e19\u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e31\u0e19\u0e40\u0e2d\u0e07 \u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e1c\u0e19\u0e31\u0e07\u0e02\u0e2d\u0e07\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e19\u0e35\u0e49\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a\u0e40\u0e07\u0e32\/\u0e14\u0e49\u0e32\u0e19\u0e41\u0e1a\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e08\u0e30\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e23\u0e30\u0e17\u0e31\u0e1a\u0e43\u0e08\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01 \u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e17\u0e35\u0e48\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e17\u0e35\u0e48\u0e04\u0e38\u0e13\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23 \u0e2b\u0e32\u0e01\u0e04\u0e38\u0e13\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14\u0e40\u0e07\u0e34\u0e19\u0e41\u0e15\u0e48\u0e01\u0e33\u0e25\u0e31\u0e07\u0e21\u0e2d\u0e07\u0e2b\u0e32\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e23\u0e39\u0e2b\u0e23\u0e32 \u0e43\u0e2b\u0e49\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2b\u0e34\u0e19\u0e2d\u0e48\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e02\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 Red Ledges \u0e43\u0e19 Utah \u0e21\u0e35\u0e17\u0e38\u0e01\u0e2a\u0e48\u0e27\u0e19\u0e17\u0e35\u0e48\u0e04\u0e38\u0e13\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e43\u0e19\u0e22\u0e48\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e17\u0e35\u0e48\u0e2b\u0e23\u0e39\u0e2b\u0e23\u0e32: \u0e21\u0e38\u0e21\u0e21\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e14\u0e35 \u0e23\u0e30\u0e22\u0e30\u0e17\u0e32\u0e07\u0e02\u0e2d\u0e07\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e04\u0e37\u0e2d \u0e2a\u0e19\u0e32\u0e21\u0e01\u0e2d\u0e25\u0e4c\u0e1f Jack Nicklaus Signature \u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e2b\u0e25\u0e32\u0e22\u0e1b\u0e35\u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32 \u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e08\u0e48\u0e32\u0e22\u0e1f\u0e38\u0e48\u0e21\u0e40\u0e1f\u0e37\u0e2d\u0e22\u0e43\u0e19\u0e2a\u0e2b\u0e23\u0e31\u0e10\u0e2d\u0e40\u0e21\u0e23\u0e34\u0e01\u0e32\u0e44\u0e14\u0e49\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e02\u0e36\u0e49\u0e19 \u0e40\u0e23\u0e47\u0e27\u0e01\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e08\u0e48\u0e32\u0e22\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e16\u0e36\u0e07 4 \u0e40\u0e17\u0e48\u0e32 \u0e2b\u0e23\u0e37\u0e2d\u0e25\u0e32\u0e22\u0e2b\u0e34\u0e19\u0e2d\u0e48\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e08\u0e30\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e23\u0e39\u0e2b\u0e23\u0e32\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e1e\u0e32\u0e23\u0e4c\u0e15\u0e34\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13 \u0e43\u0e19\u0e01\u0e23\u0e13\u0e35\u0e04\u0e38\u0e13\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e23\u0e39\u0e1b\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2b\u0e34\u0e19\u0e2d\u0e48\u0e2d\u0e19 \u0e41\u0e15\u0e48\u0e21\u0e35\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19\u0e17\u0e35\u0e48\u0e04\u0e31\u0e1a\u0e04\u0e31\u0e48\u0e07 \u0e14\u0e49\u0e32\u0e19\u0e25\u0e48\u0e32\u0e07\u0e19\u0e35\u0e49\u0e04\u0e37\u0e2d\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e25\u0e14\u0e02\u0e19\u0e32\u0e14\u0e1a\u0e32\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e33\u0e43\u0e1a\u0e49\u0e02\u0e2d\u0e07\u0e2b\u0e34\u0e19\u0e2d\u0e48\u0e2d\u0e19\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13 \u0e01\u0e32\u0e23\u0e1c\u0e2a\u0e21\u0e1c\u0e2a\u0e32\u0e19\u0e2b\u0e34\u0e19\u0e2d\u0e48\u0e2d\u0e19\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e43\u0e14\u0e01\u0e47\u0e44\u0e14\u0e49\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e42\u0e14\u0e22\u0e23\u0e27\u0e21\u0e14\u0e35\u0e02\u0e36\u0e49\u0e19<\/p>\n<p>\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e42\u0e15\u0e4a\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e1b\u0e49\u0e07\u0e2a\u0e35\u0e41\u0e14\u0e07\u0e15\u0e31\u0e14\u0e01\u0e31\u0e1a\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28\u0e2a\u0e35\u0e02\u0e32\u0e27\u0e08\u0e30\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e01\u0e47\u0e15\u0e32\u0e21 \u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e17\u0e35\u0e48\u0e40\u0e25\u0e47\u0e01\u0e01\u0e27\u0e48\u0e32\u0e02\u0e2d\u0e07 AirPods Pro \u0e17\u0e35\u0e48\u0e2a\u0e27\u0e21\u0e43\u0e2a\u0e48\u0e44\u0e14\u0e49\u0e1e\u0e2d\u0e14\u0e35\u0e15\u0e31\u0e27 \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e19\u0e01\u0e32\u0e23\u0e42\u0e17\u0e23\u0e14\u0e49\u0e27\u0e22\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e17\u0e35\u0e48\u0e22\u0e2d\u0e14\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21 \u0e17\u0e33\u0e43\u0e2b\u0e49 Bose \u0e19\u0e31\u0e49\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e0a\u0e21\u0e1b\u0e4c\u0e2a\u0e32\u0e22\u0e15\u0e23\u0e07\u0e44\u0e14\u0e49\u0e22\u0e32\u0e01 (\u0e17\u0e31\u0e49\u0e07\u0e04\u0e39\u0e48\u0e21\u0e35\u0e04\u0e38\u0e13\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e31\u0e19\u0e19\u0e49\u0e33\u0e01\u0e23\u0e30\u0e40\u0e0b\u0e47\u0e19\u0e41\u0e25\u0e30\u0e01\u0e31\u0e19\u0e19\u0e49\u0e33\u0e23\u0e30\u0e14\u0e31\u0e1a IPX) \u0e16\u0e39\u0e01\u0e2b\u0e25\u0e48\u0e2d\u0e2b\u0e25\u0e2d\u0e21\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e17\u0e35\u0e48\u0e41\u0e15\u0e01\u0e15\u0e48\u0e32\u0e07\u0e01\u0e31\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e34\u0e49\u0e19\u0e40\u0e0a\u0e34\u0e07\u0e0b\u0e36\u0e48\u0e07\u0e2d\u0e32\u0e08\u0e40\u0e02\u0e49\u0e32\u0e44\u0e14\u0e49\u0e01\u0e31\u0e1a\u0e1a\u0e49\u0e32\u0e19\u0e17\u0e38\u0e01\u0e2b\u0e25\u0e31\u0e07 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49 \u0e22\u0e31\u0e07\u0e2a\u0e27\u0e21\u0e43\u0e2a\u0e48\u0e2a\u0e1a\u0e32\u0e22 \u0e2b\u0e21\u0e32\u0e22\u0e40\u0e2b\u0e15\u0e38: \u0e15\u0e31\u0e27\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e02\u0e2d\u0e07 Shorex \u0e1a\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e32\u0e08\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e14\u0e34\u0e19\u0e40\u0e25\u0e48\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e14\u0e34\u0e19\u0e1b\u0e48\u0e32\u0e2b\u0e23\u0e37\u0e2d\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e2b\u0e25\u0e32\u0e22\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e17\u0e35\u0e48\u0e2d\u0e32\u0e08\u0e44\u0e21\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e21\u0e35\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e14\u0e49\u0e32\u0e19\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e David Carnoy\/ CNET \u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19\u0e0a\u0e37\u0e48\u0e19\u0e0a\u0e2d\u0e1a Nuraphones \u0e41\u0e1a\u0e1a\u0e04\u0e23\u0e2d\u0e1a\u0e2b\u0e39\u0e14\u0e31\u0e49\u0e07\u0e40\u0e14\u0e34\u0e21\u0e02\u0e2d\u0e07 Nura \u0e17\u0e35\u0e48\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e21\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e35\u0e40\u0e2d\u0e01\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e14\u0e49\u0e27\u0e22\u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e43\u0e19\u0e2b\u0e39\u0e41\u0e25\u0e30\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e31\u0e1a\u0e41\u0e15\u0e48\u0e07\u0e44\u0e14\u0e49 \u0e43\u0e19\u0e27\u0e31\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e49\u0e32\u0e22\u0e1b\u0e35\u0e40\u0e01\u0e48\u0e32 \u0e40\u0e18\u0e2d\u0e41\u0e19\u0e30\u0e19\u0e33\u0e41\u0e2d\u0e19\u0e40\u0e14\u0e2d\u0e23\u0e4c\u0e2a\u0e31\u0e19 \u0e04\u0e39\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e27\u0e48\u0e32\u0e40\u0e18\u0e2d\u0e21\u0e35\u0e41\u0e1c\u0e19\u0e17\u0e35\u0e48\u0e08\u0e30\u0e01\u0e25\u0e31\u0e1a\u0e44\u0e1b\u0e2a\u0e39\u0e48\u0e04\u0e27\u0e32\u0e21\u0e23\u0e31\u0e01\u0e43\u0e19\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e14\u0e31\u0e49\u0e07\u0e40\u0e14\u0e34\u0e21\u0e02\u0e2d\u0e07\u0e40\u0e18\u0e2d \u0e04\u0e2d\u0e25\u0e40\u0e25\u0e01\u0e0a\u0e31\u0e19\u0e2d\u0e32\u0e22\u0e38\u0e2a\u0e31\u0e49\u0e19 Sick Note (2017-2018) \u0e17\u0e35\u0e48\u0e19\u0e33\u0e41\u0e2a\u0e14\u0e07\u0e42\u0e14\u0e22\u0e23\u0e39\u0e40\u0e1e\u0e34\u0e23\u0e4c\u0e15 \u0e01\u0e23\u0e34\u0e19\u0e15\u0e4c \u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e17\u0e35\u0e48\u0e42\u0e14\u0e14\u0e40\u0e14\u0e48\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e02\u0e2d\u0e07\u0e40\u0e18\u0e2d\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32 \u0e08\u0e33\u0e19\u0e27\u0e19\u0e1b\u0e35 &#8220;\u0e23\u0e30\u0e1a\u0e1a\u0e19\u0e35\u0e49\u0e16\u0e39\u0e01\u0e19\u0e33\u0e21\u0e32\u0e43\u0e0a\u0e49\u0e40\u0e21\u0e37\u0e48\u0e2d 50 \u0e1b\u0e35\u0e17\u0e35\u0e48\u0e41\u0e25\u0e49\u0e27 \u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e17\u0e31\u0e19\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e19 15 \u0e1b\u0e35 \u0e41\u0e25\u0e30\u0e2d\u0e32\u0e22\u0e38\u0e01\u0e47\u0e41\u0e2a\u0e14\u0e07\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e47\u0e19&#8221; \u0e40\u0e18\u0e2d\u0e01\u0e25\u0e48\u0e32\u0e27 &#8220;\u0e1a\u0e32\u0e07\u0e04\u0e23\u0e31\u0e49\u0e07\u0e40\u0e23\u0e32\u0e04\u0e34\u0e14\u0e27\u0e48\u0e32 \u0e2d\u0e37\u0e21&#8221;&#8221; \u0e40\u0e18\u0e2d\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e01\u0e25\u0e48\u0e32\u0e27 \u0e2b\u0e34\u0e19\u0e2d\u0e48\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e08\u0e30\u0e16\u0e39\u0e01\u0e19\u0e33\u0e21\u0e32\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e17\u0e38\u0e01\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e40\u0e17\u0e48\u0e32\u0e17\u0e35\u0e48\u0e08\u0e30\u0e08\u0e34\u0e19\u0e15\u0e19\u0e32\u0e01\u0e32\u0e23\u0e44\u0e14\u0e49 \u0e41\u0e25\u0e30\u0e08\u0e30\u0e16\u0e39\u0e01\u0e41\u0e01\u0e30\u0e2a\u0e25\u0e31\u0e01\u0e40\u0e1b\u0e47\u0e19\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e0a\u0e48\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e48\u0e32\u0e07\u0e46<\/p>\n<p>HBO Max \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e04\u0e38\u0e13\u0e08\u0e30\u0e0a\u0e2d\u0e1a\u0e2a\u0e34\u0e48\u0e07\u0e19\u0e35\u0e49\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48\u0e01\u0e47\u0e15\u0e32\u0e21 \u0e02\u0e36\u0e49\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e27\u0e48\u0e32\u0e04\u0e38\u0e13\u0e0a\u0e2d\u0e1a Seth Rogen \u0e21\u0e32\u0e01\u0e41\u0e04\u0e48\u0e44\u0e2b\u0e19 \u0e04\u0e38\u0e13\u0e04\u0e27\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e2b\u0e34\u0e19\u0e01\u0e49\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e08\u0e32\u0e01\u0e1c\u0e39\u0e49\u0e1c\u0e25\u0e34\u0e15\u0e2b\u0e34\u0e19\u0e2d\u0e48\u0e2d\u0e19\u0e2a\u0e35\u0e41\u0e14\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07 Sipani Marbles \u0e43\u0e19\u0e1a\u0e31\u0e07\u0e01\u0e32\u0e25\u0e2d\u0e23\u0e4c \u0e2b\u0e32\u0e01\u0e04\u0e38\u0e13\u0e01\u0e33\u0e25\u0e31\u0e07\u0e15\u0e32\u0e21\u0e25\u0e48\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e49\u0e19\u0e2b\u0e32\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e40\u0e19\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e19\u0e35\u0e49 \u0e2b\u0e34\u0e19\u0e2d\u0e48\u0e2d\u0e19 Sipani \u0e43\u0e19\u0e1a\u0e31\u0e07\u0e01\u0e32\u0e25\u0e2d\u0e23\u0e4c\u0e19\u0e31\u0e49\u0e19\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e43\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e14\u0e39\u0e41\u0e04\u0e47\u0e15\u0e15\u0e32\u0e25\u0e47\u0e2d\u0e01\u0e14\u0e49\u0e32\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e02\u0e2d\u0e07 Spider-Man \u0e41\u0e25\u0e30\u0e04\u0e38\u0e13\u0e08\u0e30\u0e23\u0e39\u0e49\u0e27\u0e48\u0e32\u0e17\u0e33\u0e44\u0e21\u0e04\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e42\u0e23\u0e07\u0e25\u0e30\u0e04\u0e23\u0e2d\u0e35\u0e01\u0e04\u0e23\u0e31\u0e49\u0e07\u0e16\u0e36\u0e07\u0e40\u0e0a\u0e35\u0e22\u0e23\u0e4c\u0e17\u0e38\u0e01\u0e27\u0e34\u0e19\u0e32\u0e17\u0e35 \u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19\u0e2a\u0e35\u0e41\u0e14\u0e07\u0e40\u0e15\u0e47\u0e21\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e27\u0e34\u0e19\u0e40\u0e17\u0e08\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e19\u0e33\u0e04\u0e38\u0e13\u0e44\u0e1b\u0e2a\u0e39\u0e48\u0e22\u0e38\u0e04\u0e01\u0e48\u0e2d\u0e19\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e19\u0e48\u0e32\u0e1b\u0e23\u0e30\u0e2b\u0e25\u0e32\u0e14\u0e43\u0e08 \u0e43\u0e2b\u0e49\u0e0a\u0e48\u0e32\u0e07\u0e14\u0e39\u0e43\u0e2b\u0e49\u0e04\u0e23\u0e31\u0e1a \u0e2a\u0e34\u0e48\u0e07\u0e19\u0e35\u0e49\u0e16\u0e39\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e15\u0e48\u0e33\u0e40\u0e01\u0e34\u0e19\u0e44\u0e1b\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e41\u0e1c\u0e48\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e21\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e0a\u0e31\u0e14\u0e40\u0e08\u0e19 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e44\u0e21\u0e48\u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e31\u0e19 \u0e04\u0e38\u0e13\u0e2d\u0e32\u0e08\u0e21\u0e35\u0e40\u0e04\u0e32\u0e19\u0e4c\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e2b\u0e34\u0e19\u0e2d\u0e48\u0e2d\u0e19\u0e2a\u0e35\u0e41\u0e14\u0e07 \u0e1c\u0e39\u0e49\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e38\u0e01\u0e04\u0e19\u0e43\u0e19\u0e41\u0e15\u0e48\u0e25\u0e30\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e1a\u0e34\u0e19\u0e16\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e34\u0e14\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d \u0e25\u0e39\u0e01\u0e2b\u0e34\u0e19\u0e19\u0e35\u0e49\u0e22\u0e31\u0e07\u0e17\u0e33\u0e07\u0e32\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e1b\u0e47\u0e19 backsplash \u0e2b\u0e23\u0e37\u0e2d\u0e42\u0e21\u0e40\u0e2a\u0e04 \u0e02\u0e36\u0e49\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1e\u0e32\u0e23\u0e4c\u0e15\u0e34\u0e0a\u0e31\u0e19 TCL \u0e22\u0e31\u0e07\u0e02\u0e32\u0e22\u0e23\u0e38\u0e48\u0e19 8K \u0e02\u0e2d\u0e07\u0e0b\u0e35\u0e23\u0e35\u0e2a\u0e4c 6 \u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22 \u0e41\u0e15\u0e48\u0e09\u0e31\u0e19\u0e44\u0e21\u0e48\u0e04\u0e34\u0e14\u0e27\u0e48\u0e32\u0e21\u0e31\u0e19\u0e08\u0e30\u0e04\u0e38\u0e49\u0e21\u0e01\u0e31\u0e1a\u0e40\u0e07\u0e34\u0e19\u0e17\u0e35\u0e48\u0e08\u0e48\u0e32\u0e22\u0e40\u0e1e\u0e34\u0e48\u0e21 \u0e19\u0e2d\u0e01\u0e40\u0e2b\u0e19\u0e37\u0e2d\u0e08\u0e32\u0e01\u0e23\u0e38\u0e48\u0e19\u0e17\u0e35\u0e48\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e42\u0e14\u0e22 Google \u0e17\u0e35\u0e48\u0e09\u0e31\u0e19\u0e21\u0e35 \u0e41\u0e15\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19 (\u0e41\u0e21\u0e49\u0e27\u0e48\u0e32\u0e15\u0e32\u0e21 TCL \u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e02\u0e2d\u0e07\u0e20\u0e32\u0e1e\u0e08\u0e30\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e01\u0e31\u0e1a Roku \u0e23\u0e38\u0e48\u0e19\u0e19\u0e35\u0e49)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e2a\u0e35\u0e43\u0e14\u0e46 \u0e08\u0e30\u0e14\u0e39\u0e14\u0e35\u0e14\u0e49\u0e27\u0e22\u0e14\u0e27\u0e07\u0e15\u0e32\u0e2a\u0e35\u0e19\u0e49\u0e33\u0e15\u0e32\u0e25\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e35\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07\u0e2d\u0e33\u0e1e\u0e31\u0e19 \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e2a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[218],"tags":[],"class_list":["post-13128","post","type-post","status-publish","format-standard","hentry","category-218"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"\u0e2a\u0e35\u0e43\u0e14\u0e46 \u0e08\u0e30\u0e14\u0e39\u0e14\u0e35\u0e14\u0e49\u0e27\u0e22\u0e14\u0e27\u0e07\u0e15\u0e32\u0e2a\u0e35\u0e19\u0e49\u0e33\u0e15\u0e32\u0e25\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e35\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07\u0e2d\u0e33\u0e1e\u0e31\u0e19 \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e2a\" \/>\n\t<meta name=\"robots\" content=\"nofollow, noarchive, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"bookiessite\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/bookiessite.com\/th\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b8%a5%e0%b8%b1%e0%b8%9a%e0%b8%ab%e0%b8%81%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a3-%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b9%83%e0%b8%8a%e0%b9%89\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"th_TH\" \/>\n\t\t<meta property=\"og:site_name\" content=\"\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c\u0e40\u0e14\u0e34\u0e21\u0e1e\u0e31\u0e19 | \u0e23\u0e31\u0e1a\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c\u0e40\u0e08\u0e49\u0e32\u0e21\u0e37\u0e2d\u0e23\u0e31\u0e1a\u0e41\u0e17\u0e07\u0e17\u0e35\u0e48\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e41\u0e25\u0e30\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e17\u0e35\u0e48\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c\u0e40\u0e14\u0e34\u0e21\u0e1e\u0e31\u0e19 \u0e40\u0e1b\u0e23\u0e35\u0e22\u0e1a\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e40\u0e08\u0e49\u0e32\u0e21\u0e37\u0e2d\u0e23\u0e31\u0e1a\u0e41\u0e17\u0e07\u0e17\u0e35\u0e48\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e21\u0e1e\u0e31\u0e19\u0e01\u0e35\u0e2c\u0e32 \u0e04\u0e32\u0e2a\u0e34\u0e42\u0e19 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e21\u0e1e\u0e31\u0e19\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e23\u0e31\u0e1a\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c\u0e40\u0e14\u0e34\u0e21\u0e1e\u0e31\u0e19\u0e17\u0e35\u0e48\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e27\u0e34\u0e18\u0e35\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e40\u0e08\u0e49\u0e32\u0e21\u0e37\u0e2d\u0e23\u0e31\u0e1a\u0e41\u0e17\u0e07\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22 \u0e23\u0e31\u0e1a\u0e2d\u0e31\u0e15\u0e23\u0e32\u0e15\u0e48\u0e2d\u0e23\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14 \u0e40\u0e14\u0e34\u0e21\u0e1e\u0e31\u0e19\u0e1f\u0e23\u0e35 \u0e41\u0e25\u0e30\u0e25\u0e07\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e42\u0e1a\u0e19\u0e31\u0e2a\u0e17\u0e35\u0e48\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c\u0e40\u0e08\u0e49\u0e32\u0e21\u0e37\u0e2d\u0e23\u0e31\u0e1a\u0e41\u0e17\u0e07\u0e21\u0e49\u0e32\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\u0e04\u0e27\u0e32\u0e21\u0e25\u0e31\u0e1a\u0e2b\u0e01\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e23 \u0e27\u0e34\u0e18\u0e35\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e35\u0e40\u0e02\u0e35\u0e22\u0e27\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e33\u0e44\u0e23 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c | \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c\u0e40\u0e14\u0e34\u0e21\u0e1e\u0e31\u0e19\" \/>\n\t\t<meta property=\"og:description\" content=\"\u0e2a\u0e35\u0e43\u0e14\u0e46 \u0e08\u0e30\u0e14\u0e39\u0e14\u0e35\u0e14\u0e49\u0e27\u0e22\u0e14\u0e27\u0e07\u0e15\u0e32\u0e2a\u0e35\u0e19\u0e49\u0e33\u0e15\u0e32\u0e25\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e35\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07\u0e2d\u0e33\u0e1e\u0e31\u0e19 \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e2a\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/bookiessite.com\/th\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b8%a5%e0%b8%b1%e0%b8%9a%e0%b8%ab%e0%b8%81%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a3-%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b9%83%e0%b8%8a%e0%b9%89\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/bookiessite.com\/wp-content\/uploads\/2022\/12\/bookiessite.svg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/bookiessite.com\/wp-content\/uploads\/2022\/12\/bookiessite.svg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-12-04T12:54:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2022-12-04T12:54:00+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\u0e04\u0e27\u0e32\u0e21\u0e25\u0e31\u0e1a\u0e2b\u0e01\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e23 \u0e27\u0e34\u0e18\u0e35\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e35\u0e40\u0e02\u0e35\u0e22\u0e27\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e33\u0e44\u0e23 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c | \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c\u0e40\u0e14\u0e34\u0e21\u0e1e\u0e31\u0e19\" \/>\n\t\t<meta name=\"twitter:description\" content=\"\u0e2a\u0e35\u0e43\u0e14\u0e46 \u0e08\u0e30\u0e14\u0e39\u0e14\u0e35\u0e14\u0e49\u0e27\u0e22\u0e14\u0e27\u0e07\u0e15\u0e32\u0e2a\u0e35\u0e19\u0e49\u0e33\u0e15\u0e32\u0e25\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e35\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07\u0e2d\u0e33\u0e1e\u0e31\u0e19 \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e2a\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/bookiessite.com\/wp-content\/uploads\/2022\/12\/bookiessite.svg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/bookiessite.com\\\/th\\\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b8%a5%e0%b8%b1%e0%b8%9a%e0%b8%ab%e0%b8%81%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a3-%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b9%83%e0%b8%8a%e0%b9%89\\\/#blogposting\",\"name\":\"\\u0e04\\u0e27\\u0e32\\u0e21\\u0e25\\u0e31\\u0e1a\\u0e2b\\u0e01\\u0e1b\\u0e23\\u0e30\\u0e01\\u0e32\\u0e23 \\u0e27\\u0e34\\u0e18\\u0e35\\u0e43\\u0e0a\\u0e49\\u0e1b\\u0e23\\u0e30\\u0e42\\u0e22\\u0e0a\\u0e19\\u0e4c\\u0e08\\u0e32\\u0e01\\u0e2a\\u0e35\\u0e40\\u0e02\\u0e35\\u0e22\\u0e27\\u0e40\\u0e1e\\u0e37\\u0e48\\u0e2d\\u0e2a\\u0e23\\u0e49\\u0e32\\u0e07\\u0e18\\u0e38\\u0e23\\u0e01\\u0e34\\u0e08\\u0e17\\u0e35\\u0e48\\u0e17\\u0e33\\u0e01\\u0e33\\u0e44\\u0e23 \\u0e1c\\u0e25\\u0e34\\u0e15\\u0e20\\u0e31\\u0e13\\u0e11\\u0e4c | \\u0e40\\u0e27\\u0e47\\u0e1a\\u0e44\\u0e0b\\u0e15\\u0e4c\\u0e40\\u0e14\\u0e34\\u0e21\\u0e1e\\u0e31\\u0e19\",\"headline\":\"\\u0e04\\u0e27\\u0e32\\u0e21\\u0e25\\u0e31\\u0e1a\\u0e2b\\u0e01\\u0e1b\\u0e23\\u0e30\\u0e01\\u0e32\\u0e23 \\u0e27\\u0e34\\u0e18\\u0e35\\u0e43\\u0e0a\\u0e49\\u0e1b\\u0e23\\u0e30\\u0e42\\u0e22\\u0e0a\\u0e19\\u0e4c\\u0e08\\u0e32\\u0e01\\u0e2a\\u0e35\\u0e40\\u0e02\\u0e35\\u0e22\\u0e27\\u0e40\\u0e1e\\u0e37\\u0e48\\u0e2d\\u0e2a\\u0e23\\u0e49\\u0e32\\u0e07\\u0e18\\u0e38\\u0e23\\u0e01\\u0e34\\u0e08\\u0e17\\u0e35\\u0e48\\u0e17\\u0e33\\u0e01\\u0e33\\u0e44\\u0e23 \\u0e1c\\u0e25\\u0e34\\u0e15\\u0e20\\u0e31\\u0e13\\u0e11\\u0e4c\",\"author\":{\"@id\":\"https:\\\/\\\/bookiessite.com\\\/th\\\/author\\\/bookiessite\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/bookiessite.com\\\/th\\\/#person\"},\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/bookiessite.com\\\/th\\\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b8%a5%e0%b8%b1%e0%b8%9a%e0%b8%ab%e0%b8%81%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a3-%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b9%83%e0%b8%8a%e0%b9%89\\\/#articleImage\",\"url\":\"https:\\\/\\\/bookiessite.com\\\/wp-content\\\/litespeed\\\/avatar\\\/dc6b217f598387868ff2e5f4100560d6.jpg?ver=1788140211\",\"width\":96,\"height\":96,\"caption\":\"bookiessite\"},\"datePublished\":\"2022-12-04T12:54:00+00:00\",\"dateModified\":\"2022-12-04T12:54:00+00:00\",\"inLanguage\":\"th\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bookiessite.com\\\/th\\\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b8%a5%e0%b8%b1%e0%b8%9a%e0%b8%ab%e0%b8%81%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a3-%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b9%83%e0%b8%8a%e0%b9%89\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/bookiessite.com\\\/th\\\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b8%a5%e0%b8%b1%e0%b8%9a%e0%b8%ab%e0%b8%81%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a3-%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b9%83%e0%b8%8a%e0%b9%89\\\/#webpage\"},\"articleSection\":\"\\u0e1a\\u0e25\\u0e47\\u0e2d\\u0e01, Optional\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bookiessite.com\\\/th\\\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b8%a5%e0%b8%b1%e0%b8%9a%e0%b8%ab%e0%b8%81%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a3-%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b9%83%e0%b8%8a%e0%b9%89\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/bookiessite.com\\\/th\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bookiessite.com\\\/th\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/bookiessite.com\\\/th\\\/category\\\/%e0%b8%9a%e0%b8%a5%e0%b9%87%e0%b8%ad%e0%b8%81\\\/#listItem\",\"name\":\"\\u0e1a\\u0e25\\u0e47\\u0e2d\\u0e01\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/bookiessite.com\\\/th\\\/category\\\/%e0%b8%9a%e0%b8%a5%e0%b9%87%e0%b8%ad%e0%b8%81\\\/#listItem\",\"position\":2,\"name\":\"\\u0e1a\\u0e25\\u0e47\\u0e2d\\u0e01\",\"item\":\"https:\\\/\\\/bookiessite.com\\\/th\\\/category\\\/%e0%b8%9a%e0%b8%a5%e0%b9%87%e0%b8%ad%e0%b8%81\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/bookiessite.com\\\/th\\\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b8%a5%e0%b8%b1%e0%b8%9a%e0%b8%ab%e0%b8%81%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a3-%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b9%83%e0%b8%8a%e0%b9%89\\\/#listItem\",\"name\":\"\\u0e04\\u0e27\\u0e32\\u0e21\\u0e25\\u0e31\\u0e1a\\u0e2b\\u0e01\\u0e1b\\u0e23\\u0e30\\u0e01\\u0e32\\u0e23 \\u0e27\\u0e34\\u0e18\\u0e35\\u0e43\\u0e0a\\u0e49\\u0e1b\\u0e23\\u0e30\\u0e42\\u0e22\\u0e0a\\u0e19\\u0e4c\\u0e08\\u0e32\\u0e01\\u0e2a\\u0e35\\u0e40\\u0e02\\u0e35\\u0e22\\u0e27\\u0e40\\u0e1e\\u0e37\\u0e48\\u0e2d\\u0e2a\\u0e23\\u0e49\\u0e32\\u0e07\\u0e18\\u0e38\\u0e23\\u0e01\\u0e34\\u0e08\\u0e17\\u0e35\\u0e48\\u0e17\\u0e33\\u0e01\\u0e33\\u0e44\\u0e23 \\u0e1c\\u0e25\\u0e34\\u0e15\\u0e20\\u0e31\\u0e13\\u0e11\\u0e4c\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/bookiessite.com\\\/th\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/bookiessite.com\\\/th\\\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b8%a5%e0%b8%b1%e0%b8%9a%e0%b8%ab%e0%b8%81%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a3-%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b9%83%e0%b8%8a%e0%b9%89\\\/#listItem\",\"position\":3,\"name\":\"\\u0e04\\u0e27\\u0e32\\u0e21\\u0e25\\u0e31\\u0e1a\\u0e2b\\u0e01\\u0e1b\\u0e23\\u0e30\\u0e01\\u0e32\\u0e23 \\u0e27\\u0e34\\u0e18\\u0e35\\u0e43\\u0e0a\\u0e49\\u0e1b\\u0e23\\u0e30\\u0e42\\u0e22\\u0e0a\\u0e19\\u0e4c\\u0e08\\u0e32\\u0e01\\u0e2a\\u0e35\\u0e40\\u0e02\\u0e35\\u0e22\\u0e27\\u0e40\\u0e1e\\u0e37\\u0e48\\u0e2d\\u0e2a\\u0e23\\u0e49\\u0e32\\u0e07\\u0e18\\u0e38\\u0e23\\u0e01\\u0e34\\u0e08\\u0e17\\u0e35\\u0e48\\u0e17\\u0e33\\u0e01\\u0e33\\u0e44\\u0e23 \\u0e1c\\u0e25\\u0e34\\u0e15\\u0e20\\u0e31\\u0e13\\u0e11\\u0e4c\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/bookiessite.com\\\/th\\\/category\\\/%e0%b8%9a%e0%b8%a5%e0%b9%87%e0%b8%ad%e0%b8%81\\\/#listItem\",\"name\":\"\\u0e1a\\u0e25\\u0e47\\u0e2d\\u0e01\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bookiessite.com\\\/th\\\/#person\",\"name\":\"bookiessite\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/bookiessite.com\\\/th\\\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b8%a5%e0%b8%b1%e0%b8%9a%e0%b8%ab%e0%b8%81%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a3-%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b9%83%e0%b8%8a%e0%b9%89\\\/#personImage\",\"url\":\"https:\\\/\\\/bookiessite.com\\\/wp-content\\\/litespeed\\\/avatar\\\/dc6b217f598387868ff2e5f4100560d6.jpg?ver=1788140211\",\"width\":96,\"height\":96,\"caption\":\"bookiessite\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bookiessite.com\\\/th\\\/author\\\/bookiessite\\\/#author\",\"url\":\"https:\\\/\\\/bookiessite.com\\\/th\\\/author\\\/bookiessite\\\/\",\"name\":\"bookiessite\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/bookiessite.com\\\/th\\\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b8%a5%e0%b8%b1%e0%b8%9a%e0%b8%ab%e0%b8%81%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a3-%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b9%83%e0%b8%8a%e0%b9%89\\\/#authorImage\",\"url\":\"https:\\\/\\\/bookiessite.com\\\/wp-content\\\/litespeed\\\/avatar\\\/dc6b217f598387868ff2e5f4100560d6.jpg?ver=1788140211\",\"width\":96,\"height\":96,\"caption\":\"bookiessite\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bookiessite.com\\\/th\\\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b8%a5%e0%b8%b1%e0%b8%9a%e0%b8%ab%e0%b8%81%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a3-%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b9%83%e0%b8%8a%e0%b9%89\\\/#webpage\",\"url\":\"https:\\\/\\\/bookiessite.com\\\/th\\\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b8%a5%e0%b8%b1%e0%b8%9a%e0%b8%ab%e0%b8%81%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a3-%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b9%83%e0%b8%8a%e0%b9%89\\\/\",\"name\":\"\\u0e04\\u0e27\\u0e32\\u0e21\\u0e25\\u0e31\\u0e1a\\u0e2b\\u0e01\\u0e1b\\u0e23\\u0e30\\u0e01\\u0e32\\u0e23 \\u0e27\\u0e34\\u0e18\\u0e35\\u0e43\\u0e0a\\u0e49\\u0e1b\\u0e23\\u0e30\\u0e42\\u0e22\\u0e0a\\u0e19\\u0e4c\\u0e08\\u0e32\\u0e01\\u0e2a\\u0e35\\u0e40\\u0e02\\u0e35\\u0e22\\u0e27\\u0e40\\u0e1e\\u0e37\\u0e48\\u0e2d\\u0e2a\\u0e23\\u0e49\\u0e32\\u0e07\\u0e18\\u0e38\\u0e23\\u0e01\\u0e34\\u0e08\\u0e17\\u0e35\\u0e48\\u0e17\\u0e33\\u0e01\\u0e33\\u0e44\\u0e23 \\u0e1c\\u0e25\\u0e34\\u0e15\\u0e20\\u0e31\\u0e13\\u0e11\\u0e4c | \\u0e40\\u0e27\\u0e47\\u0e1a\\u0e44\\u0e0b\\u0e15\\u0e4c\\u0e40\\u0e14\\u0e34\\u0e21\\u0e1e\\u0e31\\u0e19\",\"description\":\"\\u0e2a\\u0e35\\u0e43\\u0e14\\u0e46 \\u0e08\\u0e30\\u0e14\\u0e39\\u0e14\\u0e35\\u0e14\\u0e49\\u0e27\\u0e22\\u0e14\\u0e27\\u0e07\\u0e15\\u0e32\\u0e2a\\u0e35\\u0e19\\u0e49\\u0e33\\u0e15\\u0e32\\u0e25\\u0e2b\\u0e23\\u0e37\\u0e2d\\u0e2a\\u0e35\\u0e40\\u0e2b\\u0e25\\u0e37\\u0e2d\\u0e07\\u0e2d\\u0e33\\u0e1e\\u0e31\\u0e19 \\u0e15\\u0e31\\u0e49\\u0e07\\u0e41\\u0e15\\u0e48\\u0e2a\",\"inLanguage\":\"th\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bookiessite.com\\\/th\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bookiessite.com\\\/th\\\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b8%a5%e0%b8%b1%e0%b8%9a%e0%b8%ab%e0%b8%81%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a3-%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b9%83%e0%b8%8a%e0%b9%89\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/bookiessite.com\\\/th\\\/author\\\/bookiessite\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/bookiessite.com\\\/th\\\/author\\\/bookiessite\\\/#author\"},\"datePublished\":\"2022-12-04T12:54:00+00:00\",\"dateModified\":\"2022-12-04T12:54:00+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bookiessite.com\\\/th\\\/#website\",\"url\":\"https:\\\/\\\/bookiessite.com\\\/th\\\/\",\"name\":\"Betting sites\",\"alternateName\":\"Betting sites\",\"description\":\"\\u0e23\\u0e31\\u0e1a\\u0e02\\u0e49\\u0e2d\\u0e21\\u0e39\\u0e25\\u0e40\\u0e27\\u0e47\\u0e1a\\u0e44\\u0e0b\\u0e15\\u0e4c\\u0e40\\u0e08\\u0e49\\u0e32\\u0e21\\u0e37\\u0e2d\\u0e23\\u0e31\\u0e1a\\u0e41\\u0e17\\u0e07\\u0e17\\u0e35\\u0e48\\u0e14\\u0e35\\u0e17\\u0e35\\u0e48\\u0e2a\\u0e38\\u0e14\\u0e41\\u0e25\\u0e30\\u0e04\\u0e33\\u0e41\\u0e19\\u0e30\\u0e19\\u0e33\\u0e17\\u0e35\\u0e48\\u0e40\\u0e27\\u0e47\\u0e1a\\u0e44\\u0e0b\\u0e15\\u0e4c\\u0e40\\u0e14\\u0e34\\u0e21\\u0e1e\\u0e31\\u0e19 \\u0e40\\u0e1b\\u0e23\\u0e35\\u0e22\\u0e1a\\u0e40\\u0e17\\u0e35\\u0e22\\u0e1a\\u0e40\\u0e08\\u0e49\\u0e32\\u0e21\\u0e37\\u0e2d\\u0e23\\u0e31\\u0e1a\\u0e41\\u0e17\\u0e07\\u0e17\\u0e35\\u0e48\\u0e14\\u0e35\\u0e17\\u0e35\\u0e48\\u0e2a\\u0e38\\u0e14\\u0e2a\\u0e33\\u0e2b\\u0e23\\u0e31\\u0e1a\\u0e01\\u0e32\\u0e23\\u0e40\\u0e14\\u0e34\\u0e21\\u0e1e\\u0e31\\u0e19\\u0e01\\u0e35\\u0e2c\\u0e32 \\u0e04\\u0e32\\u0e2a\\u0e34\\u0e42\\u0e19 \\u0e41\\u0e25\\u0e30\\u0e01\\u0e32\\u0e23\\u0e40\\u0e14\\u0e34\\u0e21\\u0e1e\\u0e31\\u0e19\\u0e2d\\u0e2d\\u0e19\\u0e44\\u0e25\\u0e19\\u0e4c \\u0e23\\u0e31\\u0e1a\\u0e40\\u0e27\\u0e47\\u0e1a\\u0e44\\u0e0b\\u0e15\\u0e4c\\u0e40\\u0e14\\u0e34\\u0e21\\u0e1e\\u0e31\\u0e19\\u0e17\\u0e35\\u0e48\\u0e14\\u0e35\\u0e17\\u0e35\\u0e48\\u0e2a\\u0e38\\u0e14\\u0e40\\u0e01\\u0e35\\u0e48\\u0e22\\u0e27\\u0e01\\u0e31\\u0e1a\\u0e27\\u0e34\\u0e18\\u0e35\\u0e40\\u0e25\\u0e37\\u0e2d\\u0e01\\u0e08\\u0e32\\u0e01\\u0e40\\u0e08\\u0e49\\u0e32\\u0e21\\u0e37\\u0e2d\\u0e23\\u0e31\\u0e1a\\u0e41\\u0e17\\u0e07\\u0e17\\u0e35\\u0e48\\u0e2b\\u0e25\\u0e32\\u0e01\\u0e2b\\u0e25\\u0e32\\u0e22 \\u0e23\\u0e31\\u0e1a\\u0e2d\\u0e31\\u0e15\\u0e23\\u0e32\\u0e15\\u0e48\\u0e2d\\u0e23\\u0e2d\\u0e07\\u0e17\\u0e35\\u0e48\\u0e14\\u0e35\\u0e17\\u0e35\\u0e48\\u0e2a\\u0e38\\u0e14 \\u0e40\\u0e14\\u0e34\\u0e21\\u0e1e\\u0e31\\u0e19\\u0e1f\\u0e23\\u0e35 \\u0e41\\u0e25\\u0e30\\u0e25\\u0e07\\u0e17\\u0e30\\u0e40\\u0e1a\\u0e35\\u0e22\\u0e19\\u0e42\\u0e1a\\u0e19\\u0e31\\u0e2a\\u0e17\\u0e35\\u0e48\\u0e40\\u0e27\\u0e47\\u0e1a\\u0e44\\u0e0b\\u0e15\\u0e4c\\u0e40\\u0e08\\u0e49\\u0e32\\u0e21\\u0e37\\u0e2d\\u0e23\\u0e31\\u0e1a\\u0e41\\u0e17\\u0e07\\u0e21\\u0e49\\u0e32\",\"inLanguage\":\"th\",\"publisher\":{\"@id\":\"https:\\\/\\\/bookiessite.com\\\/th\\\/#person\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\u0e04\u0e27\u0e32\u0e21\u0e25\u0e31\u0e1a\u0e2b\u0e01\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e23 \u0e27\u0e34\u0e18\u0e35\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e35\u0e40\u0e02\u0e35\u0e22\u0e27\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e33\u0e44\u0e23 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c | \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c\u0e40\u0e14\u0e34\u0e21\u0e1e\u0e31\u0e19","description":"\u0e2a\u0e35\u0e43\u0e14\u0e46 \u0e08\u0e30\u0e14\u0e39\u0e14\u0e35\u0e14\u0e49\u0e27\u0e22\u0e14\u0e27\u0e07\u0e15\u0e32\u0e2a\u0e35\u0e19\u0e49\u0e33\u0e15\u0e32\u0e25\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e35\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07\u0e2d\u0e33\u0e1e\u0e31\u0e19 \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e2a","canonical_url":"https:\/\/bookiessite.com\/th\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b8%a5%e0%b8%b1%e0%b8%9a%e0%b8%ab%e0%b8%81%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a3-%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b9%83%e0%b8%8a%e0%b9%89\/","robots":"nofollow, noarchive, max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/bookiessite.com\/th\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b8%a5%e0%b8%b1%e0%b8%9a%e0%b8%ab%e0%b8%81%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a3-%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b9%83%e0%b8%8a%e0%b9%89\/#blogposting","name":"\u0e04\u0e27\u0e32\u0e21\u0e25\u0e31\u0e1a\u0e2b\u0e01\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e23 \u0e27\u0e34\u0e18\u0e35\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e35\u0e40\u0e02\u0e35\u0e22\u0e27\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e33\u0e44\u0e23 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c | \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c\u0e40\u0e14\u0e34\u0e21\u0e1e\u0e31\u0e19","headline":"\u0e04\u0e27\u0e32\u0e21\u0e25\u0e31\u0e1a\u0e2b\u0e01\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e23 \u0e27\u0e34\u0e18\u0e35\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e35\u0e40\u0e02\u0e35\u0e22\u0e27\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e33\u0e44\u0e23 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c","author":{"@id":"https:\/\/bookiessite.com\/th\/author\/bookiessite\/#author"},"publisher":{"@id":"https:\/\/bookiessite.com\/th\/#person"},"image":{"@type":"ImageObject","@id":"https:\/\/bookiessite.com\/th\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b8%a5%e0%b8%b1%e0%b8%9a%e0%b8%ab%e0%b8%81%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a3-%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b9%83%e0%b8%8a%e0%b9%89\/#articleImage","url":"https:\/\/bookiessite.com\/wp-content\/litespeed\/avatar\/dc6b217f598387868ff2e5f4100560d6.jpg?ver=1788140211","width":96,"height":96,"caption":"bookiessite"},"datePublished":"2022-12-04T12:54:00+00:00","dateModified":"2022-12-04T12:54:00+00:00","inLanguage":"th","mainEntityOfPage":{"@id":"https:\/\/bookiessite.com\/th\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b8%a5%e0%b8%b1%e0%b8%9a%e0%b8%ab%e0%b8%81%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a3-%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b9%83%e0%b8%8a%e0%b9%89\/#webpage"},"isPartOf":{"@id":"https:\/\/bookiessite.com\/th\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b8%a5%e0%b8%b1%e0%b8%9a%e0%b8%ab%e0%b8%81%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a3-%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b9%83%e0%b8%8a%e0%b9%89\/#webpage"},"articleSection":"\u0e1a\u0e25\u0e47\u0e2d\u0e01, Optional"},{"@type":"BreadcrumbList","@id":"https:\/\/bookiessite.com\/th\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b8%a5%e0%b8%b1%e0%b8%9a%e0%b8%ab%e0%b8%81%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a3-%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b9%83%e0%b8%8a%e0%b9%89\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/bookiessite.com\/th\/#listItem","position":1,"name":"Home","item":"https:\/\/bookiessite.com\/th\/","nextItem":{"@type":"ListItem","@id":"https:\/\/bookiessite.com\/th\/category\/%e0%b8%9a%e0%b8%a5%e0%b9%87%e0%b8%ad%e0%b8%81\/#listItem","name":"\u0e1a\u0e25\u0e47\u0e2d\u0e01"}},{"@type":"ListItem","@id":"https:\/\/bookiessite.com\/th\/category\/%e0%b8%9a%e0%b8%a5%e0%b9%87%e0%b8%ad%e0%b8%81\/#listItem","position":2,"name":"\u0e1a\u0e25\u0e47\u0e2d\u0e01","item":"https:\/\/bookiessite.com\/th\/category\/%e0%b8%9a%e0%b8%a5%e0%b9%87%e0%b8%ad%e0%b8%81\/","nextItem":{"@type":"ListItem","@id":"https:\/\/bookiessite.com\/th\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b8%a5%e0%b8%b1%e0%b8%9a%e0%b8%ab%e0%b8%81%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a3-%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b9%83%e0%b8%8a%e0%b9%89\/#listItem","name":"\u0e04\u0e27\u0e32\u0e21\u0e25\u0e31\u0e1a\u0e2b\u0e01\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e23 \u0e27\u0e34\u0e18\u0e35\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e35\u0e40\u0e02\u0e35\u0e22\u0e27\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e33\u0e44\u0e23 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c"},"previousItem":{"@type":"ListItem","@id":"https:\/\/bookiessite.com\/th\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/bookiessite.com\/th\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b8%a5%e0%b8%b1%e0%b8%9a%e0%b8%ab%e0%b8%81%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a3-%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b9%83%e0%b8%8a%e0%b9%89\/#listItem","position":3,"name":"\u0e04\u0e27\u0e32\u0e21\u0e25\u0e31\u0e1a\u0e2b\u0e01\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e23 \u0e27\u0e34\u0e18\u0e35\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e35\u0e40\u0e02\u0e35\u0e22\u0e27\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e33\u0e44\u0e23 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c","previousItem":{"@type":"ListItem","@id":"https:\/\/bookiessite.com\/th\/category\/%e0%b8%9a%e0%b8%a5%e0%b9%87%e0%b8%ad%e0%b8%81\/#listItem","name":"\u0e1a\u0e25\u0e47\u0e2d\u0e01"}}]},{"@type":"Person","@id":"https:\/\/bookiessite.com\/th\/#person","name":"bookiessite","image":{"@type":"ImageObject","@id":"https:\/\/bookiessite.com\/th\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b8%a5%e0%b8%b1%e0%b8%9a%e0%b8%ab%e0%b8%81%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a3-%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b9%83%e0%b8%8a%e0%b9%89\/#personImage","url":"https:\/\/bookiessite.com\/wp-content\/litespeed\/avatar\/dc6b217f598387868ff2e5f4100560d6.jpg?ver=1788140211","width":96,"height":96,"caption":"bookiessite"}},{"@type":"Person","@id":"https:\/\/bookiessite.com\/th\/author\/bookiessite\/#author","url":"https:\/\/bookiessite.com\/th\/author\/bookiessite\/","name":"bookiessite","image":{"@type":"ImageObject","@id":"https:\/\/bookiessite.com\/th\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b8%a5%e0%b8%b1%e0%b8%9a%e0%b8%ab%e0%b8%81%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a3-%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b9%83%e0%b8%8a%e0%b9%89\/#authorImage","url":"https:\/\/bookiessite.com\/wp-content\/litespeed\/avatar\/dc6b217f598387868ff2e5f4100560d6.jpg?ver=1788140211","width":96,"height":96,"caption":"bookiessite"}},{"@type":"WebPage","@id":"https:\/\/bookiessite.com\/th\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b8%a5%e0%b8%b1%e0%b8%9a%e0%b8%ab%e0%b8%81%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a3-%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b9%83%e0%b8%8a%e0%b9%89\/#webpage","url":"https:\/\/bookiessite.com\/th\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b8%a5%e0%b8%b1%e0%b8%9a%e0%b8%ab%e0%b8%81%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a3-%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b9%83%e0%b8%8a%e0%b9%89\/","name":"\u0e04\u0e27\u0e32\u0e21\u0e25\u0e31\u0e1a\u0e2b\u0e01\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e23 \u0e27\u0e34\u0e18\u0e35\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e35\u0e40\u0e02\u0e35\u0e22\u0e27\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e33\u0e44\u0e23 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c | \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c\u0e40\u0e14\u0e34\u0e21\u0e1e\u0e31\u0e19","description":"\u0e2a\u0e35\u0e43\u0e14\u0e46 \u0e08\u0e30\u0e14\u0e39\u0e14\u0e35\u0e14\u0e49\u0e27\u0e22\u0e14\u0e27\u0e07\u0e15\u0e32\u0e2a\u0e35\u0e19\u0e49\u0e33\u0e15\u0e32\u0e25\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e35\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07\u0e2d\u0e33\u0e1e\u0e31\u0e19 \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e2a","inLanguage":"th","isPartOf":{"@id":"https:\/\/bookiessite.com\/th\/#website"},"breadcrumb":{"@id":"https:\/\/bookiessite.com\/th\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b8%a5%e0%b8%b1%e0%b8%9a%e0%b8%ab%e0%b8%81%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a3-%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b9%83%e0%b8%8a%e0%b9%89\/#breadcrumblist"},"author":{"@id":"https:\/\/bookiessite.com\/th\/author\/bookiessite\/#author"},"creator":{"@id":"https:\/\/bookiessite.com\/th\/author\/bookiessite\/#author"},"datePublished":"2022-12-04T12:54:00+00:00","dateModified":"2022-12-04T12:54:00+00:00"},{"@type":"WebSite","@id":"https:\/\/bookiessite.com\/th\/#website","url":"https:\/\/bookiessite.com\/th\/","name":"Betting sites","alternateName":"Betting sites","description":"\u0e23\u0e31\u0e1a\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c\u0e40\u0e08\u0e49\u0e32\u0e21\u0e37\u0e2d\u0e23\u0e31\u0e1a\u0e41\u0e17\u0e07\u0e17\u0e35\u0e48\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e41\u0e25\u0e30\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e17\u0e35\u0e48\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c\u0e40\u0e14\u0e34\u0e21\u0e1e\u0e31\u0e19 \u0e40\u0e1b\u0e23\u0e35\u0e22\u0e1a\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e40\u0e08\u0e49\u0e32\u0e21\u0e37\u0e2d\u0e23\u0e31\u0e1a\u0e41\u0e17\u0e07\u0e17\u0e35\u0e48\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e21\u0e1e\u0e31\u0e19\u0e01\u0e35\u0e2c\u0e32 \u0e04\u0e32\u0e2a\u0e34\u0e42\u0e19 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e21\u0e1e\u0e31\u0e19\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e23\u0e31\u0e1a\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c\u0e40\u0e14\u0e34\u0e21\u0e1e\u0e31\u0e19\u0e17\u0e35\u0e48\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e27\u0e34\u0e18\u0e35\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e40\u0e08\u0e49\u0e32\u0e21\u0e37\u0e2d\u0e23\u0e31\u0e1a\u0e41\u0e17\u0e07\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22 \u0e23\u0e31\u0e1a\u0e2d\u0e31\u0e15\u0e23\u0e32\u0e15\u0e48\u0e2d\u0e23\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14 \u0e40\u0e14\u0e34\u0e21\u0e1e\u0e31\u0e19\u0e1f\u0e23\u0e35 \u0e41\u0e25\u0e30\u0e25\u0e07\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e42\u0e1a\u0e19\u0e31\u0e2a\u0e17\u0e35\u0e48\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c\u0e40\u0e08\u0e49\u0e32\u0e21\u0e37\u0e2d\u0e23\u0e31\u0e1a\u0e41\u0e17\u0e07\u0e21\u0e49\u0e32","inLanguage":"th","publisher":{"@id":"https:\/\/bookiessite.com\/th\/#person"}}]},"og:locale":"th_TH","og:site_name":"\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c\u0e40\u0e14\u0e34\u0e21\u0e1e\u0e31\u0e19 | \u0e23\u0e31\u0e1a\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c\u0e40\u0e08\u0e49\u0e32\u0e21\u0e37\u0e2d\u0e23\u0e31\u0e1a\u0e41\u0e17\u0e07\u0e17\u0e35\u0e48\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e41\u0e25\u0e30\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e17\u0e35\u0e48\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c\u0e40\u0e14\u0e34\u0e21\u0e1e\u0e31\u0e19 \u0e40\u0e1b\u0e23\u0e35\u0e22\u0e1a\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e40\u0e08\u0e49\u0e32\u0e21\u0e37\u0e2d\u0e23\u0e31\u0e1a\u0e41\u0e17\u0e07\u0e17\u0e35\u0e48\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e21\u0e1e\u0e31\u0e19\u0e01\u0e35\u0e2c\u0e32 \u0e04\u0e32\u0e2a\u0e34\u0e42\u0e19 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e21\u0e1e\u0e31\u0e19\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e23\u0e31\u0e1a\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c\u0e40\u0e14\u0e34\u0e21\u0e1e\u0e31\u0e19\u0e17\u0e35\u0e48\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e27\u0e34\u0e18\u0e35\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e40\u0e08\u0e49\u0e32\u0e21\u0e37\u0e2d\u0e23\u0e31\u0e1a\u0e41\u0e17\u0e07\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22 \u0e23\u0e31\u0e1a\u0e2d\u0e31\u0e15\u0e23\u0e32\u0e15\u0e48\u0e2d\u0e23\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14 \u0e40\u0e14\u0e34\u0e21\u0e1e\u0e31\u0e19\u0e1f\u0e23\u0e35 \u0e41\u0e25\u0e30\u0e25\u0e07\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e42\u0e1a\u0e19\u0e31\u0e2a\u0e17\u0e35\u0e48\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c\u0e40\u0e08\u0e49\u0e32\u0e21\u0e37\u0e2d\u0e23\u0e31\u0e1a\u0e41\u0e17\u0e07\u0e21\u0e49\u0e32","og:type":"article","og:title":"\u0e04\u0e27\u0e32\u0e21\u0e25\u0e31\u0e1a\u0e2b\u0e01\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e23 \u0e27\u0e34\u0e18\u0e35\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e35\u0e40\u0e02\u0e35\u0e22\u0e27\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e33\u0e44\u0e23 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c | \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c\u0e40\u0e14\u0e34\u0e21\u0e1e\u0e31\u0e19","og:description":"\u0e2a\u0e35\u0e43\u0e14\u0e46 \u0e08\u0e30\u0e14\u0e39\u0e14\u0e35\u0e14\u0e49\u0e27\u0e22\u0e14\u0e27\u0e07\u0e15\u0e32\u0e2a\u0e35\u0e19\u0e49\u0e33\u0e15\u0e32\u0e25\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e35\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07\u0e2d\u0e33\u0e1e\u0e31\u0e19 \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e2a","og:url":"https:\/\/bookiessite.com\/th\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b8%a5%e0%b8%b1%e0%b8%9a%e0%b8%ab%e0%b8%81%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a3-%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b9%83%e0%b8%8a%e0%b9%89\/","og:image":"https:\/\/bookiessite.com\/wp-content\/uploads\/2022\/12\/bookiessite.svg","og:image:secure_url":"https:\/\/bookiessite.com\/wp-content\/uploads\/2022\/12\/bookiessite.svg","article:published_time":"2022-12-04T12:54:00+00:00","article:modified_time":"2022-12-04T12:54:00+00:00","twitter:card":"summary_large_image","twitter:title":"\u0e04\u0e27\u0e32\u0e21\u0e25\u0e31\u0e1a\u0e2b\u0e01\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e23 \u0e27\u0e34\u0e18\u0e35\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e35\u0e40\u0e02\u0e35\u0e22\u0e27\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e33\u0e44\u0e23 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c | \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c\u0e40\u0e14\u0e34\u0e21\u0e1e\u0e31\u0e19","twitter:description":"\u0e2a\u0e35\u0e43\u0e14\u0e46 \u0e08\u0e30\u0e14\u0e39\u0e14\u0e35\u0e14\u0e49\u0e27\u0e22\u0e14\u0e27\u0e07\u0e15\u0e32\u0e2a\u0e35\u0e19\u0e49\u0e33\u0e15\u0e32\u0e25\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e35\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07\u0e2d\u0e33\u0e1e\u0e31\u0e19 \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e2a","twitter:image":"https:\/\/bookiessite.com\/wp-content\/uploads\/2022\/12\/bookiessite.svg"},"aioseo_meta_data":{"post_id":"13128","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2022-12-06 03:08:05","updated":"2025-06-09 07:00:22","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/bookiessite.com\/th\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/bookiessite.com\/th\/category\/%e0%b8%9a%e0%b8%a5%e0%b9%87%e0%b8%ad%e0%b8%81\/\" title=\"\u0e1a\u0e25\u0e47\u0e2d\u0e01\">\u0e1a\u0e25\u0e47\u0e2d\u0e01<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t\u0e04\u0e27\u0e32\u0e21\u0e25\u0e31\u0e1a\u0e2b\u0e01\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e23 \u0e27\u0e34\u0e18\u0e35\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e35\u0e40\u0e02\u0e35\u0e22\u0e27\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e33\u0e44\u0e23 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/bookiessite.com\/th\/"},{"label":"\u0e1a\u0e25\u0e47\u0e2d\u0e01","link":"https:\/\/bookiessite.com\/th\/category\/%e0%b8%9a%e0%b8%a5%e0%b9%87%e0%b8%ad%e0%b8%81\/"},{"label":"\u0e04\u0e27\u0e32\u0e21\u0e25\u0e31\u0e1a\u0e2b\u0e01\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e23 \u0e27\u0e34\u0e18\u0e35\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e35\u0e40\u0e02\u0e35\u0e22\u0e27\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e33\u0e44\u0e23 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c","link":"https:\/\/bookiessite.com\/th\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b8%a5%e0%b8%b1%e0%b8%9a%e0%b8%ab%e0%b8%81%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a3-%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b9%83%e0%b8%8a%e0%b9%89\/"}],"acf":[],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false},"uagb_author_info":{"display_name":"bookiessite","author_link":"https:\/\/bookiessite.com\/th\/author\/bookiessite\/"},"uagb_comment_info":0,"uagb_excerpt":"\u0e2a\u0e35\u0e43\u0e14\u0e46 \u0e08\u0e30\u0e14\u0e39\u0e14\u0e35\u0e14\u0e49\u0e27\u0e22\u0e14\u0e27\u0e07\u0e15\u0e32\u0e2a\u0e35\u0e19\u0e49\u0e33\u0e15\u0e32\u0e25\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e35\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07\u0e2d\u0e33\u0e1e\u0e31\u0e19 \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e2a&hellip;","_links":{"self":[{"href":"https:\/\/bookiessite.com\/th\/wp-json\/wp\/v2\/posts\/13128","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bookiessite.com\/th\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bookiessite.com\/th\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bookiessite.com\/th\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bookiessite.com\/th\/wp-json\/wp\/v2\/comments?post=13128"}],"version-history":[{"count":0,"href":"https:\/\/bookiessite.com\/th\/wp-json\/wp\/v2\/posts\/13128\/revisions"}],"wp:attachment":[{"href":"https:\/\/bookiessite.com\/th\/wp-json\/wp\/v2\/media?parent=13128"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bookiessite.com\/th\/wp-json\/wp\/v2\/categories?post=13128"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bookiessite.com\/th\/wp-json\/wp\/v2\/tags?post=13128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}